{"id":753,"date":"2023-08-07T09:18:57","date_gmt":"2023-08-07T07:18:57","guid":{"rendered":"https:\/\/prezbiopia.pl\/konferencja23\/?page_id=753"},"modified":"2023-08-18T09:10:32","modified_gmt":"2023-08-18T07:10:32","slug":"strona-glowna","status":"publish","type":"page","link":"https:\/\/prezbiopia.pl\/konferencja23\/en\/strona-glowna\/","title":{"rendered":"Strona g\u0142\u00f3wna"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-overlay\" style=\"background:#d3b5a7\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"843\" src=\"https:\/\/prezbiopia.pl\/konferencja23\/wp-content\/uploads\/2023\/08\/Kopia-Kopia-Przypadki-Kliniczne-w-Okulistyce-2022.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/prezbiopia.pl\/konferencja23\/wp-content\/uploads\/2023\/08\/Kopia-Kopia-Przypadki-Kliniczne-w-Okulistyce-2022.png 2000w, https:\/\/prezbiopia.pl\/konferencja23\/wp-content\/uploads\/2023\/08\/Kopia-Kopia-Przypadki-Kliniczne-w-Okulistyce-2022-300x126.png 300w, https:\/\/prezbiopia.pl\/konferencja23\/wp-content\/uploads\/2023\/08\/Kopia-Kopia-Przypadki-Kliniczne-w-Okulistyce-2022-1024x432.png 1024w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_242268fa height_medium\" id=\"program\"><div class=\"l-section-overlay\" style=\"background:#f0f0f6\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"w-text us_custom_03b3ee3e\"><span class=\"w-text-h\"><span class=\"w-text-value\">Programme<\/span><\/span><\/h2><h3 class=\"w-text us_custom_aa271a07\"><span class=\"w-text-h\"><span class=\"w-text-value\">PRESBYOPIA 2023<\/span><\/span><\/h3><div class=\"w-separator us_custom_93f78f00 size_custom with_line width_default thick_5 style_solid color_secondary align_center\" style=\"height:5px\"><div class=\"w-separator-h\"><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:6rem\" id=\"i694\"><style>@media(max-width:1024px){ #i694{height:5rem!important}}@media(max-width:600px){ #i694{height:4rem!important}}<\/style><\/div><div class=\"w-hwrapper align_none valign_top\" style=\"--hwrapper-gap:0\"><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>01:30 \u2013 01:35 CEST<\/p>\n<\/div><\/div><\/div><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Opening of the conference<br \/>\n<strong>Prof. Andrzej Grzybowski<\/strong><\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper align_none valign_top\" style=\"--hwrapper-gap:0\"><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>01:35 \u2013 02:00 CEST<\/p>\n<\/div><\/div><\/div><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">OPENING LECTURE &#8211;<\/span> <span class=\"OYPEnA text-decoration-none text-strikethrough-none\">Wincenty Fukala lecture<\/span> <\/strong><\/p>\n<\/div><\/div><\/div><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><b>Discussion<\/b><\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper align_none valign_top\" style=\"--hwrapper-gap:0\"><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>02:00 \u2013 03:30 CEST<\/p>\n<\/div><\/div><\/div><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">SESSION I &#8211;<\/span> <span class=\"OYPEnA text-decoration-none text-strikethrough-none\">Recent developments in presbyopia<\/span><\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-hwrapper align_none valign_top\" style=\"--hwrapper-gap:0\"><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>03:30 &#8211; 03:35 CEST<\/p>\n<\/div><\/div><\/div><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Break<\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-separator us_custom_dd184a0a size_medium with_line width_default thick_5 style_solid color_secondary align_center\"><div class=\"w-separator-h\"><\/div><\/div><div class=\"w-hwrapper align_none valign_top\" style=\"--hwrapper-gap:0\"><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>03:35 &#8211; 04:14 CEST<\/p>\n<\/div><\/div><\/div><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">SESSION II &#8211;<\/span> <span class=\"OYPEnA text-decoration-none text-strikethrough-none\">Case reports in presbyopia<\/span><\/p>\n<\/div><\/div><\/div><\/div><div class=\"w-separator us_custom_dd184a0a size_medium with_line width_default thick_5 style_solid color_secondary align_center\"><div class=\"w-separator-h\"><\/div><\/div><div class=\"w-hwrapper align_none valign_top\" style=\"--hwrapper-gap:0\"><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>04:14 &#8211; 04:15 PM CEST<\/p>\n<\/div><\/div><\/div><div class=\"w-vwrapper align_none valign_top\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>The end of the conference<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"ProgrammePRESBYOPIA 202301:30 \u2013 01:35 CEST Opening of the conference Prof. Andrzej Grzybowski 01:35 \u2013 02:00 CEST OPENING LECTURE &#8211; Wincenty Fukala lecture Discussion 02:00 \u2013 03:30 CEST SESSION I &#8211; Recent developments in presbyopia 03:30 &#8211; 03:35 CEST Break 03:35 &#8211; 04:14 CEST SESSION II &#8211; Case reports in presbyopia 04:14 &#8211; 04:15 PM CEST...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/pages\/753"}],"collection":[{"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/comments?post=753"}],"version-history":[{"count":4,"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/pages\/753\/revisions"}],"predecessor-version":[{"id":809,"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/pages\/753\/revisions\/809"}],"wp:attachment":[{"href":"https:\/\/prezbiopia.pl\/konferencja23\/en\/wp-json\/wp\/v2\/media?parent=753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}